{"id":129,"date":"2017-07-23T13:52:29","date_gmt":"2017-07-23T13:52:29","guid":{"rendered":"https:\/\/kdmeusite.com.br\/projetos\/colegio\/?page_id=129"},"modified":"2023-09-19T22:56:11","modified_gmt":"2023-09-19T22:56:11","slug":"quem-somos","status":"publish","type":"page","link":"https:\/\/colegioidealsp.com.br\/portal\/quem-somos\/","title":{"rendered":"Quem Somos"},"content":{"rendered":"\n\t\t\t<style type='text\/css'>\n\t\t\t\t#sc_gallery-403 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-403 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 16.66%;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-403 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#sc_gallery-403 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see sc_gallery() in functions\/theme-shortcodes.php *\/\n\t\t\t<\/style>\n\t\t<div id='sc_gallery-403' class='gallery galleryid-129 gallery-columns-6 gallery-size-thumbnail file'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-1-1.png'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-1-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-1-1-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-1-1-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-1-1-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSPLASH AREA\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-3-1.png'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-3-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-3-1-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-3-1-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Area-Verde-3-1-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tGREEN AREA\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio.png'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tFACHADA\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-Do-Drone-2-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-Do-Drone-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-Do-Drone-2-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-Do-Drone-2-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Frente-Do-Colegio-Do-Drone-2-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tFACHADA\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-2.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-2-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-2-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-2-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-2-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tGIN\u00c1SIO DE ESPORTES\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-1_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-1_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-1_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-1_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Quadra-1_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tQUADRA POLIESPORTIVA\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantil-1.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantil-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantil-1-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantil-1-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantil-1-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA INFANTIL\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantill.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantill-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantill-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantill-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Infantill-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA INFANTIL\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Web.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Web-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Web-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Web-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Web-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA STEVE JOBS\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Solario-Bercario.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Solario-Bercario-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Solario-Bercario-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Solario-Bercario-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Solario-Bercario-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSOL\u00c1RIO\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Biblioteca-Area-Verde_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Biblioteca-Area-Verde_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Biblioteca-Area-Verde_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Biblioteca-Area-Verde_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Biblioteca-Area-Verde_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tBIBLIOTECA \n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Playground-Coberto_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Playground-Coberto_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Playground-Coberto_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Playground-Coberto_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Playground-Coberto_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tPLAYGROUND COBERTO\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2018\/04\/Ber\u00e7\u00e1rio-14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2018\/04\/Ber\u00e7\u00e1rio-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2018\/04\/Ber\u00e7\u00e1rio-14-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2018\/04\/Ber\u00e7\u00e1rio-14-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2018\/04\/Ber\u00e7\u00e1rio-14-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSONO BABY\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Bercario_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Bercario_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Bercario_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Bercario_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Bercario_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tREFEIT\u00d3RIO BABY\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Infantil_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Infantil_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Infantil_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Infantil_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Infantil_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tREFEIT\u00d3RIO INFANTIL\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-1_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-1_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-1_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-1_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-1_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA FUND I\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-2_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-2_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-2_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-2_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-Fund-2_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA FUND II\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-maker-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-maker-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-maker-1-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-maker-1-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Sala-maker-1-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA MAKER\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Piscina-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Piscina-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Piscina-1-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Piscina-1-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Piscina-1-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tPISCINA\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/lab1.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/lab1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/lab1-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/lab1-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/lab1-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tLABORAT\u00d3RIO\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/green-area2-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/green-area2-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/green-area2-2-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/green-area2-2-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/green-area2-2-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tGREEN AREA\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Estimulacao-1-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Estimulacao-1-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Estimulacao-1-2-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Estimulacao-1-2-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Estimulacao-1-2-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA DE ESTIMULA\u00c7\u00c3O 1\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Sala-de-Estimulacao-2-e-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Sala-de-Estimulacao-2-e-3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Sala-de-Estimulacao-2-e-3-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Sala-de-Estimulacao-2-e-3-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Sala-de-Estimulacao-2-e-3-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA DE ESTIMULA\u00c7\u00c3O 2 e 3\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/brinquedoteca-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/brinquedoteca-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/brinquedoteca-2-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/brinquedoteca-2-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/brinquedoteca-2-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tBRINQUEDOTECA\n\t\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Refeitorio-Patio-Vermelho.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Refeitorio-Patio-Vermelho-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Refeitorio-Patio-Vermelho-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Refeitorio-Patio-Vermelho-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Refeitorio-Patio-Vermelho-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tREFEIT\u00d3RIO FUNDAMENTAL E M\u00c9DIO\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/refeitorio3_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/refeitorio3_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/refeitorio3_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/refeitorio3_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/refeitorio3_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tREFEIT\u00d3RIO FUNDAMENTAL E M\u00c9DIO\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Patio-Vermelho-2_Easy-Resize.com_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Patio-Vermelho-2_Easy-Resize.com_-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Patio-Vermelho-2_Easy-Resize.com_-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Patio-Vermelho-2_Easy-Resize.com_-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Refeitorio-Patio-Vermelho-2_Easy-Resize.com_-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tREFEIT\u00d3RIO FUNDAMENTAL E M\u00c9DIO\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Cineteatro-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Cineteatro-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Cineteatro-1-150x150.jpg 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Cineteatro-1-85x85.jpg 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/08\/Cineteatro-1-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tCINETEATRO\n\t\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a href='https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Ballet.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Ballet-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Ballet-150x150.png 150w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Ballet-85x85.png 85w, https:\/\/colegioidealsp.com.br\/portal\/wp-content\/uploads\/2023\/09\/Ballet-80x80.png 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t\t<\/dt>\n\t\t\t\t\t<dd class='wp-caption-text gallery-caption'>\n\t\t\t\t\tSALA DE BALLET\n\t\t\t\t\t<\/dd><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-129","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/pages\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":34,"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/pages\/129\/revisions"}],"predecessor-version":[{"id":4657,"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/pages\/129\/revisions\/4657"}],"wp:attachment":[{"href":"https:\/\/colegioidealsp.com.br\/portal\/wp-json\/wp\/v2\/media?parent=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}